{"id":61,"date":"2021-01-25T21:01:09","date_gmt":"2021-01-25T20:01:09","guid":{"rendered":"https:\/\/surleau.corsica\/?page_id=61"},"modified":"2021-08-06T11:29:38","modified_gmt":"2021-08-06T09:29:38","slug":"accueil","status":"publish","type":"page","link":"https:\/\/surleau.corsica\/","title":{"rendered":""},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"61\" class=\"elementor elementor-61\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7581fcae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7581fcae\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1057e8f0\" data-id=\"1057e8f0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-326cf3f elementor-widget elementor-widget-heading\" data-id=\"326cf3f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Villa Surleau - Vardiola, Corse du Sud<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0b7d5e elementor-widget elementor-widget-spacer\" data-id=\"b0b7d5e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68b4e04d elementor-widget elementor-widget-text-editor\" data-id=\"68b4e04d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<!-- wp:paragraph -->\n<p>La Villa Surleau est une maison pleine de charme en bord de mer, id\u00e9ale pour des vacances en famille ou entre amis. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La terrasse vous permet de profiter en toute tranquillit\u00e9 d&rsquo;une magnifique vue sur la mer et il vous suffit simplement de traverser le jardin pour aller \u00e0 la plage ! <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La maison est \u00e9quip\u00e9e d&rsquo;un lit double au rez-de-chauss\u00e9e, ainsi que de quatre lits simples \u00e0 l&rsquo;\u00e9tage. Deux grands canap\u00e9s sont \u00e9galement disponibles dans le salon et peuvent servir de lits.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Elle poss\u00e8de \u00e9galement deux places de parking, une sur le c\u00f4t\u00e9 de la maison et une autre \u00e0 l&rsquo;arri\u00e8re (n&rsquo;h\u00e9sitez pas \u00e0 serrer les fleurs pour laisser le passage libre).<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Les \u00e9quipements mis \u00e0 votre disposition lors de votre s\u00e9jour dans la Villa Surleau :<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:columns -->\n<div class=\"wp-block-columns\"><!-- wp:column -->\n<div class=\"wp-block-column\"><!-- wp:list -->\n<ul><li>Climatisation<\/li><li>2 canap\u00e9s<\/li><li>T\u00e9l\u00e9vision<\/li><li>Wifi<\/li><li>Lecteur DVD<\/li><li>Salon de jardin<\/li><li>Barbecue \u00e9lectrique<\/li><li>Transats<\/li><li>Terrasse semi couverte<\/li><li>Un parasol<\/li><li>Une douche ext\u00e9rieur (sur le c\u00f4t\u00e9 de la maison)<\/li><\/ul>\n<!-- \/wp:list --><\/div>\n<!-- \/wp:column -->\n\n<!-- wp:column -->\n<div class=\"wp-block-column\"><!-- wp:list -->\n<ul><li>Un grille-pain<\/li><li>Deux r\u00e9frig\u00e9rateurs \/ cong\u00e9lateurs<\/li><li>Un four<\/li><li>Quatre plaques \u00e0 gaz<\/li><li>Un micro-ondes<\/li><li>Un lave-vaisselle<\/li><li>Un lave-linge<\/li><li>Un s\u00e8che-cheveux<\/li><li>Un aspirateur<\/li><li>Un fer \u00e0 repasser<\/li><li>Une machine \u00e0 caf\u00e9 Senseo<\/li><\/ul>\n<!-- \/wp:list --><\/div>\n<!-- \/wp:column --><\/div>\n<!-- \/wp:columns -->\n\n<!-- wp:paragraph -->\n\n\t\t<!-- MasterSlider -->\n\t\t<div id=\"P_MS6a977290a8a79\" class=\"master-slider-parent msl ms-parent-id-1\" style=\"\">\n\n\t\t\t\n\t\t\t<!-- MasterSlider Main -->\n\t\t\t<div id=\"MS6a977290a8a79\" class=\"master-slider ms-skin-light-6 round-skin\" >\n\t\t\t\t \t\t\t\t \n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fit\"  >\n\t\t\t\t\t<img src=\"https:\/\/surleau.corsica\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"Terrasse avec vue sur la mer\" title=\"\" data-src=\"https:\/\/surleau.corsica\/wp-content\/uploads\/2021\/01\/exterieur1-1-scaled.jpg\" \/>\n\n\n\t<img class=\"ms-thumb\" src=\"https:\/\/surleau.corsica\/wp-content\/uploads\/2021\/01\/exterieur1-1-scaled.jpg\" alt=\"Terrasse avec vue sur la mer\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=&quot;ms-tab-context&quot;><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fit\"  >\n\t\t\t\t\t<img src=\"https:\/\/surleau.corsica\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"Vue de la maison depuis la terrasse\" title=\"\" data-src=\"https:\/\/surleau.corsica\/wp-content\/uploads\/2021\/01\/exterieur6-scaled.jpg\" \/>\n\n\n\t<img class=\"ms-thumb\" src=\"https:\/\/surleau.corsica\/wp-content\/uploads\/2021\/01\/exterieur6-scaled.jpg\" alt=\"Vue de la maison depuis la terrasse\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=&quot;ms-tab-context&quot;><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fit\"  >\n\t\t\t\t\t<img src=\"https:\/\/surleau.corsica\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"Jardin avec vue sur la mer\" title=\"\" data-src=\"https:\/\/surleau.corsica\/wp-content\/uploads\/2021\/06\/IMG_46981.jpg\" \/>\n\n\n\t<img class=\"ms-thumb\" src=\"https:\/\/surleau.corsica\/wp-content\/uploads\/2021\/06\/IMG_46981.jpg\" alt=\"Jardin avec vue sur la mer\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=&quot;ms-tab-context&quot;><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fit\"  >\n\t\t\t\t\t<img src=\"https:\/\/surleau.corsica\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"Paysage avec jardin et mer\" title=\"\" data-src=\"https:\/\/surleau.corsica\/wp-content\/uploads\/2021\/06\/IMG_47011.jpg\" \/>\n\n\n\t<img class=\"ms-thumb\" src=\"https:\/\/surleau.corsica\/wp-content\/uploads\/2021\/06\/IMG_47011.jpg\" alt=\"Paysage avec jardin et mer\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=&quot;ms-tab-context&quot;><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t<!-- END MasterSlider Main -->\n\n\t\t\t \n\t\t<\/div>\n\t\t<!-- END MasterSlider -->\n\n\t\t<script>\n\t\t(function ( $ ) {\n\t\t\t\"use strict\";\n\n\t\t\t$(function () {\n\t\t\t\tvar masterslider_8a79 = new MasterSlider();\n\n\t\t\t\t\/\/ slider controls\n\t\t\t\tmasterslider_8a79.control('arrows'     ,{ autohide:false, overVideo:false  });\t\t\t\tmasterslider_8a79.control('bullets'    ,{ autohide:false, overVideo:true, dir:'h', align:'bottom' , margin:10  });\n\n\t\t\t\tmasterslider_8a79.control('thumblist'  ,{ autohide:false, overVideo:false, dir:'h', speed:17, inset:true, arrows:true, hover:false, customClass:'', align:'bottom',type:'thumbs', margin:10, width:100, height:80, space:5, fillMode:'fill'  });\n\t\t\t\tmasterslider_8a79.control('scrollbar'  ,{ autohide:true, overVideo:false, dir:'h', inset:true, align:'top', color:'#404040' , margin:10  , width:4 });\n\t\t\t\t\/\/ slider setup\n\t\t\t\tmasterslider_8a79.setup(\"MS6a977290a8a79\", {\n\t\t\t\t\t\twidth           : 1800,\n\t\t\t\t\t\theight          : 800,\n\t\t\t\t\t\tminHeight       : 0,\n\t\t\t\t\t\tspace           : 0,\n\t\t\t\t\t\tstart           : 1,\n\t\t\t\t\t\tgrabCursor      : true,\n\t\t\t\t\t\tswipe           : true,\n\t\t\t\t\t\tmouse           : true,\n\t\t\t\t\t\tlayout          : \"fullwidth\",\n\t\t\t\t\t\twheel           : true,\n\t\t\t\t\t\tautoplay        : false,\n\t\t\t\t\t\tinstantStartLayers:false,\n\t\t\t\t\t\tloop            : true,\n\t\t\t\t\t\tshuffle         : false,\n\t\t\t\t\t\tpreload         : 0,\n\t\t\t\t\t\theightLimit     : true,\n\t\t\t\t\t\tautoHeight      : false,\n\t\t\t\t\t\tsmoothHeight    : true,\n\t\t\t\t\t\tendPause        : false,\n\t\t\t\t\t\toverPause       : true,\n\t\t\t\t\t\tfillMode        : \"fill\",\n\t\t\t\t\t\tcenterControls  : false,\n\t\t\t\t\t\tstartOnAppear   : true,\n\t\t\t\t\t\tlayersMode      : \"center\",\n\t\t\t\t\t\thideLayers      : false,\n\t\t\t\t\t\tfullscreenMargin: 0,\n\t\t\t\t\t\tspeed           : 20,\n\t\t\t\t\t\tdir             : \"h\",\n\t\t\t\t\t\tparallaxMode    : 'swipe',\n\t\t\t\t\t\tview            : \"basic\"\n\t\t\t\t});\n\n\t\t\t\t\n\t\t\t\twindow.masterslider_instances = window.masterslider_instances || [];\n\t\t\t\twindow.masterslider_instances.push( masterslider_8a79 );\n\t\t\t });\n\n\t\t})(jQuery);\n\t\t<\/script>\n\n\n<!-- \/wp:paragraph -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Villa Surleau &#8211; Vardiola, Corse du Sud La Villa Surleau est une maison pleine de charme en bord de mer, id\u00e9ale pour des vacances en famille ou entre amis. La terrasse vous permet de profiter en toute tranquillit\u00e9 d&rsquo;une magnifique vue sur la mer et il vous suffit simplement de traverser le jardin pour aller \u00e0 la plage ! La maison est \u00e9quip\u00e9e d&rsquo;un lit double au rez-de-chauss\u00e9e, ainsi que de quatre lits simples \u00e0 l&rsquo;\u00e9tage. Deux grands canap\u00e9s sont \u00e9galement disponibles dans le salon et peuvent servir de lits. Elle poss\u00e8de \u00e9galement deux places de parking, une sur le c\u00f4t\u00e9 de la maison et une autre \u00e0 l&rsquo;arri\u00e8re (n&rsquo;h\u00e9sitez pas \u00e0 serrer les fleurs pour laisser le passage libre). Les \u00e9quipements mis \u00e0 votre disposition lors de votre s\u00e9jour dans la Villa Surleau : Climatisation 2 canap\u00e9s T\u00e9l\u00e9vision Wifi Lecteur DVD Salon de jardin Barbecue \u00e9lectrique Transats Terrasse semi couverte Un parasol Une douche ext\u00e9rieur (sur le c\u00f4t\u00e9 de la maison) Un grille-pain Deux r\u00e9frig\u00e9rateurs \/ cong\u00e9lateurs Un four Quatre plaques \u00e0 gaz Un micro-ondes Un lave-vaisselle Un lave-linge Un s\u00e8che-cheveux Un aspirateur Un fer \u00e0 repasser Une machine \u00e0 caf\u00e9 Senseo<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/surleau.corsica\/index.php\/wp-json\/wp\/v2\/pages\/61"}],"collection":[{"href":"https:\/\/surleau.corsica\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/surleau.corsica\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/surleau.corsica\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/surleau.corsica\/index.php\/wp-json\/wp\/v2\/comments?post=61"}],"version-history":[{"count":14,"href":"https:\/\/surleau.corsica\/index.php\/wp-json\/wp\/v2\/pages\/61\/revisions"}],"predecessor-version":[{"id":228,"href":"https:\/\/surleau.corsica\/index.php\/wp-json\/wp\/v2\/pages\/61\/revisions\/228"}],"wp:attachment":[{"href":"https:\/\/surleau.corsica\/index.php\/wp-json\/wp\/v2\/media?parent=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}